{"id":2802,"date":"2021-11-12T16:51:08","date_gmt":"2021-11-12T15:51:08","guid":{"rendered":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg"},"modified":"2021-11-12T16:51:08","modified_gmt":"2021-11-12T15:51:08","slug":"connecteur-swissmetal-contact-pins-socket","status":"inherit","type":"attachment","link":"https:\/\/swissmetal.com\/fr\/products\/connector-alloys\/connecteur-swissmetal-contact-pins-socket\/","title":{"rendered":"connecteur-swissmetal-contact-pins-socket"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"class_list":["post-2802","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>connecteur-swissmetal-contact-pins-socket - Switzerland Mastery of Copper<\/title>\n<meta name=\"description\" content=\"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"connecteur-swissmetal-contact-pins-socket - Switzerland Mastery of Copper\" \/>\n<meta property=\"og:description\" content=\"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Swissmetal Industries SA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Swissmetal-Industries-106339321702524\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"616\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/connecteur-swissmetal-contact-pins-socket.jpg\",\"url\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/connecteur-swissmetal-contact-pins-socket.jpg\",\"name\":\"connecteur-swissmetal-contact-pins-socket - Switzerland Mastery of Copper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#website\"},\"datePublished\":\"2021-11-12T15:51:08+00:00\",\"description\":\"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/connecteur-swissmetal-contact-pins-socket.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/connecteur-swissmetal-contact-pins-socket.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/connecteur-swissmetal-contact-pins-socket.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swissmetal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRODUCTS\",\"item\":\"https:\\\/\\\/swissmetal.com\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Connectors\",\"item\":\"https:\\\/\\\/swissmetal.com\\\/products\\\/connector-alloys\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"connecteur-swissmetal-contact-pins-socket\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#website\",\"url\":\"https:\\\/\\\/swissmetal.com\\\/\",\"name\":\"Swissmetal Industries SA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissmetal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#organization\",\"name\":\"Swissmetal Industries SA\",\"url\":\"https:\\\/\\\/swissmetal.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_home.png\",\"contentUrl\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_home.png\",\"width\":302,\"height\":38,\"caption\":\"Swissmetal Industries SA\"},\"image\":{\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Swissmetal-Industries-106339321702524\",\"https:\\\/\\\/www.instagram.com\\\/swissmetal_industries_sa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swissmetal-industries\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCFmWm7O1lWQX_aUzsM1qjbQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"connecteur-swissmetal-contact-pins-socket - Switzerland Mastery of Copper","description":"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg","og_locale":"fr_FR","og_type":"article","og_title":"connecteur-swissmetal-contact-pins-socket - Switzerland Mastery of Copper","og_description":"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products","og_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg","og_site_name":"Swissmetal Industries SA","article_publisher":"https:\/\/www.facebook.com\/Swissmetal-Industries-106339321702524","og_image":[{"width":616,"height":493,"url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg","url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg","name":"connecteur-swissmetal-contact-pins-socket - Switzerland Mastery of Copper","isPartOf":{"@id":"https:\/\/swissmetal.com\/#website"},"datePublished":"2021-11-12T15:51:08+00:00","description":"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products","breadcrumb":{"@id":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swissmetal.com\/"},{"@type":"ListItem","position":2,"name":"PRODUCTS","item":"https:\/\/swissmetal.com\/products\/"},{"@type":"ListItem","position":3,"name":"Connectors","item":"https:\/\/swissmetal.com\/products\/connector-alloys\/"},{"@type":"ListItem","position":4,"name":"connecteur-swissmetal-contact-pins-socket"}]},{"@type":"WebSite","@id":"https:\/\/swissmetal.com\/#website","url":"https:\/\/swissmetal.com\/","name":"Swissmetal Industries SA","description":"","publisher":{"@id":"https:\/\/swissmetal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissmetal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/swissmetal.com\/#organization","name":"Swissmetal Industries SA","url":"https:\/\/swissmetal.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swissmetal.com\/#\/schema\/logo\/image\/","url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/07\/logo_home.png","contentUrl":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/07\/logo_home.png","width":302,"height":38,"caption":"Swissmetal Industries SA"},"image":{"@id":"https:\/\/swissmetal.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Swissmetal-Industries-106339321702524","https:\/\/www.instagram.com\/swissmetal_industries_sa\/","https:\/\/www.linkedin.com\/company\/swissmetal-industries\/","https:\/\/www.youtube.com\/channel\/UCFmWm7O1lWQX_aUzsM1qjbQ"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"240\" src=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket-300x240.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket-300x240.jpg 300w, https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg 616w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":616,"height":493,"file":"2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg","sizes":{"medium":{"file":"connecteur-swissmetal-contact-pins-socket-300x240.jpg","width":300,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket-300x240.jpg"},"thumbnail":{"file":"connecteur-swissmetal-contact-pins-socket-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket-150x150.jpg"},"wptouch-new-thumbnail":{"file":"connecteur-swissmetal-contact-pins-socket-144x144.jpg","width":144,"height":144,"mime_type":"image\/jpeg","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket-144x144.jpg"},"full":{"file":"connecteur-swissmetal-contact-pins-socket.jpg","width":616,"height":493,"mime_type":"image\/jpeg","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":280,"source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/11\/connecteur-swissmetal-contact-pins-socket.jpg","_links":{"self":[{"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/media\/2802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/comments?post=2802"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":280,"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/pages\/280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}