{"id":5482,"date":"2024-08-21T07:41:22","date_gmt":"2024-08-21T06:41:22","guid":{"rendered":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png"},"modified":"2024-08-21T07:41:22","modified_gmt":"2024-08-21T06:41:22","slug":"logo-ambassadeur-grandchasseral","status":"inherit","type":"attachment","link":"https:\/\/swissmetal.com\/fr\/swissmetal-company\/grand-chasseral\/logo-ambassadeur-grandchasseral\/","title":{"rendered":"Logo-ambassadeur-grandchasseral"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"class_list":["post-5482","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Logo-ambassadeur-grandchasseral - Switzerland Mastery of Copper<\/title>\n<meta name=\"description\" content=\"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logo-ambassadeur-grandchasseral - Switzerland Mastery of Copper\" \/>\n<meta property=\"og:description\" content=\"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png\" \/>\n<meta property=\"og:site_name\" content=\"Swissmetal Industries SA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Swissmetal-Industries-106339321702524\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"747\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo-ambassadeur-grandchasseral.png\",\"url\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo-ambassadeur-grandchasseral.png\",\"name\":\"Logo-ambassadeur-grandchasseral - Switzerland Mastery of Copper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#website\"},\"datePublished\":\"2024-08-21T06:41:22+00:00\",\"description\":\"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo-ambassadeur-grandchasseral.png#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo-ambassadeur-grandchasseral.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo-ambassadeur-grandchasseral.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swissmetal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMPANY\",\"item\":\"https:\\\/\\\/swissmetal.com\\\/swissmetal-company\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grand Chasseral\",\"item\":\"https:\\\/\\\/swissmetal.com\\\/swissmetal-company\\\/grand-chasseral\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Logo-ambassadeur-grandchasseral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#website\",\"url\":\"https:\\\/\\\/swissmetal.com\\\/\",\"name\":\"Swissmetal Industries SA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissmetal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#organization\",\"name\":\"Swissmetal Industries SA\",\"url\":\"https:\\\/\\\/swissmetal.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_home.png\",\"contentUrl\":\"https:\\\/\\\/swissmetal.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_home.png\",\"width\":302,\"height\":38,\"caption\":\"Swissmetal Industries SA\"},\"image\":{\"@id\":\"https:\\\/\\\/swissmetal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Swissmetal-Industries-106339321702524\",\"https:\\\/\\\/www.instagram.com\\\/swissmetal_industries_sa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swissmetal-industries\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCFmWm7O1lWQX_aUzsM1qjbQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logo-ambassadeur-grandchasseral - Switzerland Mastery of Copper","description":"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png","og_locale":"fr_FR","og_type":"article","og_title":"Logo-ambassadeur-grandchasseral - Switzerland Mastery of Copper","og_description":"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products","og_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png","og_site_name":"Swissmetal Industries SA","article_publisher":"https:\/\/www.facebook.com\/Swissmetal-Industries-106339321702524","og_image":[{"width":2048,"height":747,"url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png","url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png","name":"Logo-ambassadeur-grandchasseral - Switzerland Mastery of Copper","isPartOf":{"@id":"https:\/\/swissmetal.com\/#website"},"datePublished":"2024-08-21T06:41:22+00:00","description":"Swissmetal Industries SA - Switzerland Mastery of Copper - Innovation and Tailored products","breadcrumb":{"@id":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swissmetal.com\/"},{"@type":"ListItem","position":2,"name":"COMPANY","item":"https:\/\/swissmetal.com\/swissmetal-company\/"},{"@type":"ListItem","position":3,"name":"Grand Chasseral","item":"https:\/\/swissmetal.com\/swissmetal-company\/grand-chasseral\/"},{"@type":"ListItem","position":4,"name":"Logo-ambassadeur-grandchasseral"}]},{"@type":"WebSite","@id":"https:\/\/swissmetal.com\/#website","url":"https:\/\/swissmetal.com\/","name":"Swissmetal Industries SA","description":"","publisher":{"@id":"https:\/\/swissmetal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissmetal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/swissmetal.com\/#organization","name":"Swissmetal Industries SA","url":"https:\/\/swissmetal.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swissmetal.com\/#\/schema\/logo\/image\/","url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/07\/logo_home.png","contentUrl":"https:\/\/swissmetal.com\/wp-content\/uploads\/2021\/07\/logo_home.png","width":302,"height":38,"caption":"Swissmetal Industries SA"},"image":{"@id":"https:\/\/swissmetal.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Swissmetal-Industries-106339321702524","https:\/\/www.instagram.com\/swissmetal_industries_sa\/","https:\/\/www.linkedin.com\/company\/swissmetal-industries\/","https:\/\/www.youtube.com\/channel\/UCFmWm7O1lWQX_aUzsM1qjbQ"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png'><img decoding=\"async\" width=\"300\" height=\"109\" src=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-300x109.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-300x109.png 300w, https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-1024x374.png 1024w, https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-768x280.png 768w, https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-1536x560.png 1536w, https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-776x283.png 776w, https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-822x300.png 822w, https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-800x292.png 800w, https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-512x187.png 512w, https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":2048,"height":747,"file":"2024\/08\/Logo-ambassadeur-grandchasseral.png","filesize":164829,"sizes":{"medium":{"file":"Logo-ambassadeur-grandchasseral-300x109.png","width":300,"height":109,"filesize":18092,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-300x109.png"},"large":{"file":"Logo-ambassadeur-grandchasseral-1024x374.png","width":1024,"height":374,"filesize":76379,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-1024x374.png"},"thumbnail":{"file":"Logo-ambassadeur-grandchasseral-150x150.png","width":150,"height":150,"filesize":9840,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-150x150.png"},"medium_large":{"file":"Logo-ambassadeur-grandchasseral-768x280.png","width":768,"height":280,"filesize":55011,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-768x280.png"},"1536x1536":{"file":"Logo-ambassadeur-grandchasseral-1536x560.png","width":1536,"height":560,"filesize":131035,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-1536x560.png"},"post-thumbnail":{"file":"Logo-ambassadeur-grandchasseral-776x283.png","width":776,"height":283,"filesize":55721,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-776x283.png"},"bravada-featured":{"file":"Logo-ambassadeur-grandchasseral-776x283.png","width":776,"height":283,"filesize":55721,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-776x283.png"},"bravada-featured-lp":{"file":"Logo-ambassadeur-grandchasseral-822x300.png","width":822,"height":300,"filesize":59301,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-822x300.png"},"bravada-featured-half":{"file":"Logo-ambassadeur-grandchasseral-800x292.png","width":800,"height":292,"filesize":57932,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-800x292.png"},"bravada-featured-third":{"file":"Logo-ambassadeur-grandchasseral-512x187.png","width":512,"height":187,"filesize":34084,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-512x187.png"},"bravada-lpbox-1":{"file":"Logo-ambassadeur-grandchasseral-412x250.png","width":412,"height":250,"filesize":28198,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-412x250.png"},"bravada-lpbox-2":{"file":"Logo-ambassadeur-grandchasseral-412x300.png","width":412,"height":300,"filesize":27785,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral-412x300.png"},"full":{"file":"Logo-ambassadeur-grandchasseral.png","width":2048,"height":747,"mime_type":"image\/png","source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":5480,"source_url":"https:\/\/swissmetal.com\/wp-content\/uploads\/2024\/08\/Logo-ambassadeur-grandchasseral.png","_links":{"self":[{"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/media\/5482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/comments?post=5482"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":5480,"href":"https:\/\/swissmetal.com\/fr\/wp-json\/wp\/v2\/pages\/5480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}